{"id":3988,"date":"2021-09-23T10:53:41","date_gmt":"2021-09-23T10:53:41","guid":{"rendered":"https:\/\/atryshealth.com\/?post_type=servicio&#038;p=3988"},"modified":"2021-09-23T10:53:51","modified_gmt":"2021-09-23T10:53:51","slug":"fish-bcr-abl1-t922","status":"publish","type":"servicio","link":"https:\/\/www.atryshealth.com\/es\/servicio\/fish-bcr-abl1-t922\/","title":{"rendered":"FISH BCR\/ABL1, t(9;22)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":1626,"template":"","patologia":[92,111],"class_list":["post-3988","servicio","type-servicio","status-publish","has-post-thumbnail","hentry","patologia-hematologia-estudios-complementarios","patologia-hibridacion-in-situ"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FISH BCR\/ABL1, t(9;22) - Atrys Health<\/title>\n<meta name=\"description\" content=\"Somos una gran compa\u00f1\u00eda. Creamos nuevas soluciones para los pacientes y el sector sanitario. Miles de profesionales de Atrys ponemos nuestra experiencia al servicio de todos, para ofrecer diagn\u00f3sticos y tratamientos de precisi\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.atryshealth.com\/es\/servicio\/fish-bcr-abl1-t922\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FISH BCR\/ABL1, t(9;22) - Atrys Health\" \/>\n<meta property=\"og:description\" content=\"Somos una gran compa\u00f1\u00eda. Creamos nuevas soluciones para los pacientes y el sector sanitario. Miles de profesionales de Atrys ponemos nuestra experiencia al servicio de todos, para ofrecer diagn\u00f3sticos y tratamientos de precisi\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.atryshealth.com\/es\/servicio\/fish-bcr-abl1-t922\/\" \/>\n<meta property=\"og:site_name\" content=\"Atrys Health\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-23T10:53:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/09\/noticia2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"350\" \/>\n\t<meta property=\"og:image:height\" content=\"363\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Atrys_Health\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/servicio\\\/fish-bcr-abl1-t922\\\/\",\"url\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/servicio\\\/fish-bcr-abl1-t922\\\/\",\"name\":\"FISH BCR\\\/ABL1, t(9;22) - Atrys Health\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/servicio\\\/fish-bcr-abl1-t922\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/servicio\\\/fish-bcr-abl1-t922\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.atryshealth.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/noticia2.jpg\",\"datePublished\":\"2021-09-23T10:53:41+00:00\",\"dateModified\":\"2021-09-23T10:53:51+00:00\",\"description\":\"Somos una gran compa\u00f1\u00eda. Creamos nuevas soluciones para los pacientes y el sector sanitario. Miles de profesionales de Atrys ponemos nuestra experiencia al servicio de todos, para ofrecer diagn\u00f3sticos y tratamientos de precisi\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/servicio\\\/fish-bcr-abl1-t922\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/servicio\\\/fish-bcr-abl1-t922\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/servicio\\\/fish-bcr-abl1-t922\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.atryshealth.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/noticia2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.atryshealth.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/noticia2.jpg\",\"width\":350,\"height\":363},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/servicio\\\/fish-bcr-abl1-t922\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Servicios\",\"item\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/servicio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"FISH BCR\\\/ABL1, t(9;22)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/\",\"name\":\"Atrys Health\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/#organization\",\"name\":\"Atrys Health S.A.\",\"url\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.atryshealth.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/atrys-logo-probar-web.png\",\"contentUrl\":\"https:\\\/\\\/www.atryshealth.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/atrys-logo-probar-web.png\",\"width\":1563,\"height\":1014,\"caption\":\"Atrys Health S.A.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Atrys_Health\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/atrys-health\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCejhA_ghBXRG1xoe9HB9pEw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FISH BCR\/ABL1, t(9;22) - Atrys Health","description":"Somos una gran compa\u00f1\u00eda. Creamos nuevas soluciones para los pacientes y el sector sanitario. Miles de profesionales de Atrys ponemos nuestra experiencia al servicio de todos, para ofrecer diagn\u00f3sticos y tratamientos de precisi\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.atryshealth.com\/es\/servicio\/fish-bcr-abl1-t922\/","og_locale":"es_ES","og_type":"article","og_title":"FISH BCR\/ABL1, t(9;22) - Atrys Health","og_description":"Somos una gran compa\u00f1\u00eda. Creamos nuevas soluciones para los pacientes y el sector sanitario. Miles de profesionales de Atrys ponemos nuestra experiencia al servicio de todos, para ofrecer diagn\u00f3sticos y tratamientos de precisi\u00f3n.","og_url":"https:\/\/www.atryshealth.com\/es\/servicio\/fish-bcr-abl1-t922\/","og_site_name":"Atrys Health","article_modified_time":"2021-09-23T10:53:51+00:00","og_image":[{"width":350,"height":363,"url":"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/09\/noticia2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Atrys_Health","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.atryshealth.com\/es\/servicio\/fish-bcr-abl1-t922\/","url":"https:\/\/www.atryshealth.com\/es\/servicio\/fish-bcr-abl1-t922\/","name":"FISH BCR\/ABL1, t(9;22) - Atrys Health","isPartOf":{"@id":"https:\/\/www.atryshealth.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.atryshealth.com\/es\/servicio\/fish-bcr-abl1-t922\/#primaryimage"},"image":{"@id":"https:\/\/www.atryshealth.com\/es\/servicio\/fish-bcr-abl1-t922\/#primaryimage"},"thumbnailUrl":"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/09\/noticia2.jpg","datePublished":"2021-09-23T10:53:41+00:00","dateModified":"2021-09-23T10:53:51+00:00","description":"Somos una gran compa\u00f1\u00eda. Creamos nuevas soluciones para los pacientes y el sector sanitario. Miles de profesionales de Atrys ponemos nuestra experiencia al servicio de todos, para ofrecer diagn\u00f3sticos y tratamientos de precisi\u00f3n.","breadcrumb":{"@id":"https:\/\/www.atryshealth.com\/es\/servicio\/fish-bcr-abl1-t922\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.atryshealth.com\/es\/servicio\/fish-bcr-abl1-t922\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.atryshealth.com\/es\/servicio\/fish-bcr-abl1-t922\/#primaryimage","url":"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/09\/noticia2.jpg","contentUrl":"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/09\/noticia2.jpg","width":350,"height":363},{"@type":"BreadcrumbList","@id":"https:\/\/www.atryshealth.com\/es\/servicio\/fish-bcr-abl1-t922\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.atryshealth.com\/es\/"},{"@type":"ListItem","position":2,"name":"Servicios","item":"https:\/\/www.atryshealth.com\/es\/servicio\/"},{"@type":"ListItem","position":3,"name":"FISH BCR\/ABL1, t(9;22)"}]},{"@type":"WebSite","@id":"https:\/\/www.atryshealth.com\/es\/#website","url":"https:\/\/www.atryshealth.com\/es\/","name":"Atrys Health","description":"","publisher":{"@id":"https:\/\/www.atryshealth.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.atryshealth.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.atryshealth.com\/es\/#organization","name":"Atrys Health S.A.","url":"https:\/\/www.atryshealth.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.atryshealth.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/12\/atrys-logo-probar-web.png","contentUrl":"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/12\/atrys-logo-probar-web.png","width":1563,"height":1014,"caption":"Atrys Health S.A."},"image":{"@id":"https:\/\/www.atryshealth.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Atrys_Health","https:\/\/es.linkedin.com\/company\/atrys-health","https:\/\/www.youtube.com\/channel\/UCejhA_ghBXRG1xoe9HB9pEw"]}]}},"_links":{"self":[{"href":"https:\/\/www.atryshealth.com\/es\/wp-json\/wp\/v2\/servicio\/3988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.atryshealth.com\/es\/wp-json\/wp\/v2\/servicio"}],"about":[{"href":"https:\/\/www.atryshealth.com\/es\/wp-json\/wp\/v2\/types\/servicio"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.atryshealth.com\/es\/wp-json\/wp\/v2\/media\/1626"}],"wp:attachment":[{"href":"https:\/\/www.atryshealth.com\/es\/wp-json\/wp\/v2\/media?parent=3988"}],"wp:term":[{"taxonomy":"patologia","embeddable":true,"href":"https:\/\/www.atryshealth.com\/es\/wp-json\/wp\/v2\/patologia?post=3988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}