{"id":462,"date":"2021-09-09T11:55:00","date_gmt":"2021-09-09T11:55:00","guid":{"rendered":"https:\/\/atryshealth.com\/?page_id=462"},"modified":"2026-03-13T09:16:12","modified_gmt":"2026-03-13T08:16:12","slug":"id","status":"publish","type":"page","link":"https:\/\/www.atryshealth.com\/es\/id\/","title":{"rendered":"I+D"},"content":{"rendered":"\r\n\r\n<section id=\"introImasd\" class=\"section section__intro section__intro__imasd\" style=\"background-image: url(https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/09\/bgIntro.jpg)\">\r\n\t<!-- INTRO I+D -->\r\n\t<div class=\"container flex flex__between flex__align__center flex__33__61\">\r\n\t\t<div class=\"mask mask__auto\">\r\n\t\t\t<img decoding=\"async\" src=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/09\/flowerBlue.svg\" alt=\"\">\r\n\t\t<\/div>\r\n\t\t<div class=\"box box__text\">\r\n\t\t\t<p class=\"fs fs28 fw fw500 blueLightColor\">Investigaci\u00f3n <\/p>\r\n\t\t\t<div class=\"separator separator__30\"><\/div>\r\n\t\t\t<h2 class=\"fs fs55 fw fw100 whiteColor\">Innovaci\u00f3n real para los retos del futuro<\/h2>\r\n\t\t\t<div class=\"separator separator__30\"><\/div>\r\n\t\t\t<p class=\"fs fs20 fw fw300 whiteColor\">Investigamos y desarrollamos cada d\u00eda nuevas soluciones tecnol\u00f3gicas para el futuro del sector sanitario. Nuestro esfuerzo aporta respuestas que ya est\u00e1n suponiendo mejoras en el diagn\u00f3stico y la medicina de precisi\u00f3n.<\/p>\r\n\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\t<\/div>\r\n<\/section> <!-- END INTRO I+D -->\n\n\r\n<section id=\"lineasInvestigacion\" class=\"section section__lineasInvestigacion\" > <!-- LINEAS INVESTIGACION -->\r\n\t\t<div class=\"container\" >\r\n\t\t\t<h2 class=\"fs fs28 fw fw500 blueLightColor\" >S\u00f3lida capacidad investigadora<\/h2>\r\n\t\t<\/div>\r\n\t\t<div class=\"container\" >\r\n\t\t\t<div class=\"grid whiteColor animate-in-down\" >\r\n\t\t\t\t\t\t\t\t\t<div class=\"blueLightColorBg\" style=\"background-color: #25b0bb\" >\r\n\t\t\t\t\t\t<span class=\"fs fs55 fw fw400 number\" >38<\/span>\r\n\t\t\t\t\t\t<p class=\"fs fs20 fw fw100\" >proyectos en 2020-2023<\/p>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"blueLightColorBg\" style=\"background-color: #187770\" >\r\n\t\t\t\t\t\t<span class=\"fs fs55 fw fw400 number\" >+6M\u20ac<\/span>\r\n\t\t\t\t\t\t<p class=\"fs fs20 fw fw100\" >invertidos al a\u00f1o en I+D<\/p>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"blueLightColorBg\" style=\"background-color: #4680ae\" >\r\n\t\t\t\t\t\t<span class=\"fs fs55 fw fw400 number\" >1.300 m<sup>2<\/sup><\/span>\r\n\t\t\t\t\t\t<p class=\"fs fs20 fw fw100\" >dedicados a la investigaci\u00f3n<\/p>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<!-- <div class=\"greenColorBg\" >\r\n\t\t\t\t\t<span class=\"fs fs55 fw fw400 number\" >2mill.\u20ac<\/span>\r\n\t\t\t\t\t<p class=\"fs fs20 fw fw100\" >Invertidos al a\u00f1o en I+D<\/p>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"blueColor2Bg\" >\r\n\t\t\t\t\t<span class=\"fs fs55 fw fw400 number\" >1.300 m<sup>2<\/sup><\/span>\r\n\t\t\t\t\t<p class=\"fs fs20 fw fw100\" >dedicados a la investigaci\u00f3n<\/p>\r\n\t\t\t\t<\/div> -->\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t<div class=\"container\" >\r\n\t\t\t<h2 class=\"fs fs55 fw fw500 blueColor\" >L\u00edneas de investigaci\u00f3n<\/h2>\r\n\t\t\t<div class=\"separator separator__30\" ><\/div>\r\n\t\t\t<div class=\"pseudoSelect\" >\r\n\t\t\t\t<div class=\"pseudoSelect__title\" >\r\n\t\t\t\t\t<span class=\"fs fs28 blueLightColor title_mardadores\" >Biopsia l\u00edquida<\/span>\r\n\t\t\t\t\t<svg viewBox=\"0 0 25 14\" >\r\n\t\t\t\t\t    <g id=\"ATRYS\" stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\">\r\n\t\t\t\t\t        <g id=\"2.2-I+D\" transform=\"translate(-851.000000, -1455.000000)\" fill=\"#044AAB\">\r\n\t\t\t\t\t            <g id=\"Lines_Investigaci\u00f3n\" transform=\"translate(409.000000, 1354.000000)\">\r\n\t\t\t\t\t                <g id=\"Group-4\" transform=\"translate(156.000000, 84.000000)\">\r\n\t\t\t\t\t                    <polygon id=\"Path-Copy\" transform=\"translate(298.622987, 24.000000) scale(-1, 1) rotate(-90.000000) translate(-298.622987, -24.000000) \" points=\"294.491949 24 305.245975 34.7540255 304 36 292 24 304 12 305.245975 13.2459745\"><\/polygon>\r\n\t\t\t\t\t                <\/g>\r\n\t\t\t\t\t            <\/g>\r\n\t\t\t\t\t        <\/g>\r\n\t\t\t\t\t    <\/g>\r\n\t\t\t\t\t<\/svg>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"pseudoSelect__content selector selector_marcadores\" >\r\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"fs fs20 fw fw500 blueColor pseudoSelect__content__1\" data-target=\"Biopsia l\u00edquida\" data-slug=\"biopsia-liquida\" >Biopsia l\u00edquida<\/h3>\r\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"fs fs20 fw fw500 blueColor pseudoSelect__content__1\" data-target=\"Nuevos marcadores\" data-slug=\"nuevos-marcadores\" >Nuevos marcadores<\/h3>\r\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"fs fs20 fw fw500 blueColor pseudoSelect__content__1\" data-target=\"Plataformas de integraci\u00f3n\" data-slug=\"plataformas-de-integracion\" >Plataformas de integraci\u00f3n<\/h3>\r\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"fs fs20 fw fw500 blueColor pseudoSelect__content__1\" data-target=\"IA para el diagn\u00f3stico\" data-slug=\"ia-diagnostico\" >IA para el diagn\u00f3stico<\/h3>\r\n\t\t\t\t\t\t\t\t\t\t<!-- <h3 class=\"fs fs20 fw fw500 blueColor pseudoSelect__content__2\" >Marcador 2<\/h3>\r\n\t\t\t\t\t<h3 class=\"fs fs20 fw fw500 blueColor pseudoSelect__content__3\" >Marcador 3<\/h3> -->\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t<style><\/style>\r\n\t\t\t<div class=\"text viewr_selector_marcadores\" >\r\n\t\t\t\t\t\t\t\t\t<p class=\"fs fs20 fw fw100 \"  data-target=\"Biopsia l\u00edquida\">Aplicamos procesos diagn\u00f3sticos menos invasivos, que permiten hallar marcadores tumorales mediante muestras de sangre.<\/p>\r\n\t\t\t\t\t\t\t\t\t<p class=\"fs fs20 fw fw100 hide\"  data-target=\"Nuevos marcadores\">Mejoramos la calidad de diagn\u00f3stico y pron\u00f3stico para una medicina personalizada m\u00e1s eficiente.<\/p>\r\n\t\t\t\t\t\t\t\t\t<p class=\"fs fs20 fw fw100 hide\"  data-target=\"Plataformas de integraci\u00f3n\">Desarrollamos estrategias de Big Data para gestionar mejor la informaci\u00f3n de los pacientes y optimizar la toma de decisiones m\u00e9dica.<\/p>\r\n\t\t\t\t\t\t\t\t\t<p class=\"fs fs20 fw fw100 hide\"  data-target=\"IA para el diagn\u00f3stico\">Incrementamos la precisi\u00f3n cl\u00ednica aplicando los \u00faltimos avances en Inteligencia Artificial al diagn\u00f3stico automatizado por imagen.<\/p>\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t<\/div>\r\n\t\t\t<div class=\"cover cover__buttons\"  >\r\n\r\n\t\t\t\t\t\t\t\t<a \r\n\t\t\t\t\tclass=\"fs fs16 fw fw500 button button__small button__green uppercase link-page-proyectos-slug\" href=\"https:\/\/atryshealth.com\/proyectos\/biopsia-liquida\" \r\n\t\t\t\t\ttarget=\"\" \r\n\t\t\t\t\tdata-url=\"https:\/\/atryshealth.com\/proyectos\/\"\r\n\t\t\t\t\t>\r\n\t\t\t\t\tSABER M\u00c1S\t\t\t\t\t\t\r\n\t\t\t\t\t<\/a>\r\n\r\n\t\t\t\t<a class=\"fs fs16 fw fw500 button  button__blue uppercase\" href=\"https:\/\/atryshealth.com\/proyectos\/\" target=\"\" title=\"Todos los proyectos\">Todos los proyectos<\/a>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/section> <!-- END LINEAS INVESTIGACION -->\n\n\r\n<section id=\"articulosPatentes\" class=\"section section__articulosPatentes greyLightColorBg\" > \r\n\t<div class=\"container\" >\r\n\t\t<div class=\"box box__text\" >\r\n\t\t\t<h2 class=\"fs fs55 fw fw500 blueColor\" >Art\u00edculos y patentes<\/h2>\r\n\t\t\t<div class=\"separator separator__20\" ><\/div>\r\n\t\t\t<p class=\"fs fs20 fw fw100\" >Como parte de la actividad del \u00e1rea de I+D, publicamos con asiduidad en revistas de prestigio y registramos patentes internacionales. Consulta nuestra producci\u00f3n cient\u00edfica e industrial.<\/p>\r\n\t\t\t<div class=\"separator separator__40\" ><\/div>\r\n\t\t\t<a class=\"fs fs16 fw fw500 button button__small button__green uppercase\" href=\"https:\/\/atryshealth.com\/articulos-y-patentes\/\" target=\"\" title=\"SABER M\u00c1S\" >SABER M\u00c1S<\/a>\r\n\t\t<\/div>\r\n\t\t<div class=\"mask\" >\r\n\t\t\t<img decoding=\"async\" src=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/09\/articulosImg.png\" alt=\"\" >\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/section> \n\n\r\n<section id=\"noticiasDoble\" class=\"section section__noticiasDoble\">\r\n\t<!-- NOTICIAS DOBLE -->\r\n\t\t\t\t\t\t<div class=\"container\">\r\n\t\t\t\t<div class=\"mask animate-in-left\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\" title=\"\"><img decoding=\"async\" src=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/09\/El-corazon-de-nuestra-competitividad-1.jpg\" alt=\"\"><\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<div class=\"box box__text animate-in-right\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"fs fs55 fw fw500 blueColor\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\" title=\"\">El coraz\u00f3n de nuestra competitividad<\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h2>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"separator separator__20\"><\/div>\r\n\t\t\t\t\t\t<div class=\"fs fs20 fw fw100 content-with-p\"><p>La I+D es parte de nuestro ADN. Investigar nos permite mantener la competitividad cient\u00edfica. Invertir en innovaci\u00f3n tecnol\u00f3gica nos permite ofrecer cada d\u00eda mejores respuestas para los pacientes y servicios m\u00e1s eficientes para el sector de la salud.<\/p>\n<\/div>\r\n\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"separator separator__40\"><\/div>\r\n\t\t\t\t\t\t<a href=\"#\" class=\"fs fs16 fw fw500 blueLightColor uppercase Din\" title=\"\"><\/a>\r\n\t\t\t\t\t\r\n\r\n\r\n\t\t\t\t\t\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"container\">\r\n\t\t\t\t<div class=\"box box__text animate-in-left\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"fs fs55 fw fw500 blueColor\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\" title=\"\">Una posici\u00f3n privilegiada para el I+D<\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h2>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"separator separator__20\"><\/div>\r\n\t\t\t\t\t\t<div class=\"fs fs20 fw fw100 content-with-p\"><p>Nuestra variedad de disciplinas sit\u00faa el \u00e1rea de I+D en una posici\u00f3n privilegiada para encabezar la innovaci\u00f3n en varias \u00e1reas de la salud. Contamos con una vasta base de datos cl\u00ednicos de alta calidad, con la que nutrimos nuestros proyectos.<\/p>\n<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"separator separator__40\"><\/div>\r\n\t\t\t\t\t\t<a href=\"#\" class=\"fs fs16 fw fw500 blueLightColor uppercase Din\" title=\"\"><\/a>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<div class=\"mask animate-in-right\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\" title=\"\"><img decoding=\"async\" src=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/09\/Una-posicion-privilegiada.jpg\" alt=\"\"><\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t<\/section> <!-- END NOTICIAS DOBLE -->\n\n\r\n\r\n\r\n\t<section id=\"conveniosFormacion\" class=\"section section__conveniosFormacion blueLightColorBg\" > <!-- CONVENIOS FORMACION -->\r\n\t\t<div class=\"container\" >\r\n\t\t\t<div class=\"box box__text alignCenter whiteColor\" >\r\n\t\t\t\t<h2 class=\"fs fs55 fw fw500\" >Convenios de investigaci\u00f3n y formaci\u00f3n<\/h2>\r\n\t\t\t\t<div class=\"separator separator__20\" ><\/div>\r\n\t\t\t\t<div class=\"fs fs20 fw fw100\" ><p>Hemos suscrito convenios de investigaci\u00f3n y formaci\u00f3n con diversas universidades, como <strong>la Universidad Europea (UE),<\/strong> <strong>la Universidad Polit\u00e9cnica de Madrid (UPM)<\/strong>, <strong> la Universidad Aut\u00f3noma de Barcelona (UAB), la Universidad Nacional Abierta a Distancia de Colombia (UNAD), la Universidad de Concepci\u00f3n de Chile (UdeC) <\/strong><strong>o la Universitat Oberta de Catalunya (UOC)<\/strong>. Los convenios tienen por objetivo ofrecer a los estudiantes una perspectiva de trabajo diferente a la obtenida en las pr\u00e1cticas de la universidad. Permiten mejorar la calidad de la docencia, completando las clases te\u00f3ricas, los seminarios y las pr\u00e1cticas universitarias con formaci\u00f3n pr\u00e1ctica recibida en un \u00e1mbito profesional. Asimismo, facilitan la progresiva relaci\u00f3n del alumno con las empresas, ayudando en su posterior incorporaci\u00f3n en el mundo laboral.<\/p>\n<\/div>\r\n\t\t\t\t<div class=\"separator separator__80\" ><\/div>\r\n\t\t\t\t<div class=\"grid slid-logos-partners\" >\r\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"\" target=\"_blank\" title=\"\" >\r\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2023\/07\/Atrys_Logos_Formacion_CEU-2.svg\" alt=\"\" >\r\n\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"\" target=\"_blank\" title=\"\" >\r\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2023\/07\/Atrys_Logos_Formacion_JAVERIANA-2.svg\" alt=\"\" >\r\n\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"\" target=\"_blank\" title=\"\" >\r\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2023\/07\/Atrys_Logos_Formacion_UE-2.svg\" alt=\"\" >\r\n\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"\" target=\"_blank\" title=\"\" >\r\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2023\/07\/Atrys_Logos_Formacion_UFV-2.svg\" alt=\"\" >\r\n\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"\" target=\"_blank\" title=\"\" >\r\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2023\/07\/Atrys_Logos_Formacion_UNAD-2.svg\" alt=\"\" >\r\n\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"\" target=\"_blank\" title=\"\" >\r\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2023\/07\/Atrys_Logos_Formacion_UPM-2.svg\" alt=\"\" >\r\n\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"\" target=\"_blank\" title=\"\" >\r\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2023\/05\/logo-01.png\" alt=\"\" >\r\n\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"\" target=\"_blank\" title=\"\" >\r\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2023\/05\/logo-02.png\" alt=\"\" >\r\n\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"\" target=\"_blank\" title=\"\" >\r\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2023\/05\/logo-04.png\" alt=\"\" >\r\n\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"\" target=\"_blank\" title=\"\" >\r\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2023\/05\/logo-07.png\" alt=\"\" >\r\n\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"\" target=\"_blank\" title=\"\" >\r\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2023\/05\/logo-05.png\" alt=\"\" >\r\n\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"\" target=\"_blank\" title=\"\" >\r\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2023\/07\/Atrys_Logos_Formacion_UDEC-1.svg\" alt=\"\" >\r\n\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"\" target=\"_blank\" title=\"\" >\r\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2023\/08\/Atrys_Logos_Formacion_UPF_UPF-1.svg\" alt=\"\" >\r\n\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/section> <!-- END CONVENIOS FORMACION -->\r\n\r\n\r\n\r\n\n\n\n<section class=\"wp-block-group section has-white-color has-text-color has-background has-link-color wp-elements-de27414f16d2183cc8a007654ac4d631 is-vertical is-content-justification-center is-layout-flex wp-container-core-group-is-layout-4b2eccd6 wp-block-group-is-layout-flex\" style=\"background-color:#25b0bb\">\n<div class=\"wp-block-columns container is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-center has-x-large-font-size\">Participa en la V Edici\u00f3n Premios C\u00e1tedra UB-Atrys Radioterapia Personalizada&nbsp;<\/h2>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center container is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2026\/03\/cartel-premios-catedra-edited-1024x683.jpg\" alt=\"\" class=\"wp-image-28042\" srcset=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2026\/03\/cartel-premios-catedra-edited-1024x683.jpg 1024w, https:\/\/www.atryshealth.com\/wp-content\/uploads\/2026\/03\/cartel-premios-catedra-edited-300x200.jpg 300w, https:\/\/www.atryshealth.com\/wp-content\/uploads\/2026\/03\/cartel-premios-catedra-edited-768x512.jpg 768w, https:\/\/www.atryshealth.com\/wp-content\/uploads\/2026\/03\/cartel-premios-catedra-edited-1536x1024.jpg 1536w, https:\/\/www.atryshealth.com\/wp-content\/uploads\/2026\/03\/cartel-premios-catedra-edited-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<section id=\"faqs\" class=\"premio section section__avisos legales\" > <!-- AVISO LEGAL -->\n\t<div class=\"container container__content\" >\n\t\t<div class=\"box box__text\" >\n\t\t<p>Se lanza la V edici\u00f3n de los Premios de investigaci\u00f3n en Radioterapia Personalizada, vinculados a la C\u00e1tedra UB Atrys creada en 2021. El objetivo es premiar la excelencia y la innovaci\u00f3n en la investigaci\u00f3n, as\u00ed como impulsar la difusi\u00f3n de conocimientos en este \u00e1rea crucial para el avance en el tratamiento del c\u00e1ncer.<\/p>\n<p><span style=\"color: #044aab;\"><a style=\"color: #044aab;\" href=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2026\/03\/Bases-convocatoria.pdf\">&#8211; Bases de la convocatoria<\/a><\/span><\/p>\n<p><a href=\"https:\/\/www.ub.edu\/eadministracio\/IG.html\"><span style=\"color: #044aab;\">&#8211; Registro de candidaturas<\/span><\/a> (Disponible hasta el 17 de abril de 2026)<\/p>\n<p><a href=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2026\/03\/Tutorial-Presentacion-Candidatura-2026.pdf\"><span style=\"color: #044aab;\">&#8211; Instrucciones para realizar el registro\u00a0<\/span><\/a><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/section> <!-- END AVISO LEGAL --><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns container is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-video\"><video height=\"1080\" style=\"aspect-ratio: 1920 \/ 1080;\" width=\"1920\" controls poster=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2026\/03\/imagen-3.png\" src=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2026\/03\/VideoConvocatoriaPremiosCatedra2026_v2_low.mp4\" playsinline><\/video><\/figure>\n\n\n\n<div style=\"height:75px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n<\/div>\n<\/section>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\" id=\"premios\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n<p><\/p>\n\n\n\n<div style=\"height:80px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\r\n\r\n\r\n\r\n\r\n<section id=\"partners\" class=\"section section__partners blueColor2Bg\" > <!-- PARTNERS -->\r\n\t<div class=\"container\" >\r\n\t\t<div class=\"box box__text alignCenter whiteColor\" >\r\n\t\t\t<h2 class=\"fs fs55 fw fw500\" >Financiadores<\/h2>\r\n\t\t\t<div class=\"separator separator__80\" ><\/div>\r\n\t\t\t<div class=\"grid slid-logos-partners\" >\r\n\t\t\t\t\t\t\t\t\t<a href=\"\" target=\"_blank\" title=\"\" >\r\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/09\/10-Logo-CaixaBank-copia-e1632921208238.png\" alt=\"\" >\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t<a href=\"\" target=\"_blank\" title=\"\" >\r\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/09\/UNION-EUROPEA.png\" alt=\"\" >\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t<a href=\"\" target=\"_blank\" title=\"\" >\r\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/09\/SANTANDER-LOGO.png\" alt=\"\" >\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t<a href=\"\" target=\"_blank\" title=\"\" >\r\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/09\/IMI.png\" alt=\"\" >\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t<a href=\"\" target=\"_blank\" title=\"\" >\r\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/09\/EFPIA-e1632921296682.png\" alt=\"\" >\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t<a href=\"\" target=\"_blank\" title=\"\" >\r\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/09\/16-feder-innterconecta-copia.png\" alt=\"\" >\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t<a href=\"\" target=\"_blank\" title=\"\" >\r\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/09\/14-CRUE-Logo-copia.png\" alt=\"\" >\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t<a href=\"\" target=\"_blank\" title=\"\" >\r\n\t\t\t\t\t\t<img decoding=\"async\" src=\"\" alt=\"\" >\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t<a href=\"\" target=\"_blank\" title=\"\" >\r\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/09\/9-Accio-feder-Logo-copia-e1632921193720.png\" alt=\"\" >\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t<a href=\"\" target=\"_blank\" title=\"\" >\r\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/09\/8-EUREKA_logo2-copia-e1632921166203.png\" alt=\"\" >\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t<a href=\"\" target=\"_blank\" title=\"\" >\r\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/09\/7-Eurostars-Logo-copia-e1632921326714.png\" alt=\"\" >\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t<a href=\"\" target=\"_blank\" title=\"\" >\r\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/09\/2-CDTI-Logo-copia.png\" alt=\"\" >\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t<a href=\"\" target=\"_blank\" title=\"\" >\r\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/09\/1-Ministerio-EU-copia.png\" alt=\"\" >\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/section> <!-- END PARTNERS -->\r\n\r\n\n\n\r\n\r\n\r\n\r\n<section id=\"slidePartners\" class=\"section section__slidePartners section__borderBottom \" >\r\n\t<!-- SLIDE PARTNERS -->\r\n\t<div class=\"container\">\r\n\t\t<div class=\"single-item single-item__full slider_testimonials\">\r\n\t\t\t<!-- Slider -->\r\n\t\t\t\t\t\t\t<div class=\"slide__item \">\r\n\t\t\t\t\t<!-- Slide item -->\r\n\t\t\t\t\t<div class=\"box\">\r\n\t\t\t\t\t\t<div class=\"cite\">\r\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.atryshealth.com\/wp-content\/themes\/atrys\/assets\/img\/comillasGreen.svg\">\r\n\t\t\t\t\t\t\t<div class=\"separator separator__20\"><\/div>\r\n\t\t\t\t\t\t\t<blockquote class=\"fs fs30 fw fw500 blueColor\">El mejor recurso de Atrys son las personas, que llevan en su ADN la investigaci\u00f3n e innovaci\u00f3n en salud, con la m\u00e1xima calidad.\r\n<\/blockquote>\r\n\t\t\t\t\t\t\t<div class=\"text\">\r\n\t\t\t\t\t\t\t\t<h3 class=\"fs fs28 fw fw500 blueColor\">Vithas<\/h3>\r\n\t\t\t\t\t\t\t\t<p class=\"fs fs16 fw fw100\">Angel Ayuso Sacido, PhD Director Cient\u00edfico Corporativo en Vithas Hospital<\/p>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div> <!-- End Slide item -->\r\n\t\t\t\t\t\t\t<div class=\"slide__item \">\r\n\t\t\t\t\t<!-- Slide item -->\r\n\t\t\t\t\t<div class=\"box\">\r\n\t\t\t\t\t\t<div class=\"cite\">\r\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.atryshealth.com\/wp-content\/themes\/atrys\/assets\/img\/comillasGreen.svg\">\r\n\t\t\t\t\t\t\t<div class=\"separator separator__20\"><\/div>\r\n\t\t\t\t\t\t\t<blockquote class=\"fs fs30 fw fw500 blueColor\">Trabajar y colaborar con personas afines a ti siempre es m\u00e1s f\u00e1cil. Desde Leitat pensamos que adem\u00e1s del nivel profesional cient\u00edfico-t\u00e9cnico de Atrys Health, lo que les hace destacar es su calidad humana. Es nuestro partner ideal para desarrollar proyectos de R&#038;D para contribuir a la mejora de la salud humana.<\/blockquote>\r\n\t\t\t\t\t\t\t<div class=\"text\">\r\n\t\t\t\t\t\t\t\t<h3 class=\"fs fs28 fw fw500 blueColor\">Leitat<\/h3>\r\n\t\t\t\t\t\t\t\t<p class=\"fs fs16 fw fw100\">Francesc Mitjans, Director de Innovaci\u00f3n Health &#038; Biomedicine del Leitat Technological Center<\/p>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div> <!-- End Slide item -->\r\n\t\t\t\t\t\t\t<div class=\"slide__item \">\r\n\t\t\t\t\t<!-- Slide item -->\r\n\t\t\t\t\t<div class=\"box\">\r\n\t\t\t\t\t\t<div class=\"cite\">\r\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.atryshealth.com\/wp-content\/themes\/atrys\/assets\/img\/comillasGreen.svg\">\r\n\t\t\t\t\t\t\t<div class=\"separator separator__20\"><\/div>\r\n\t\t\t\t\t\t\t<blockquote class=\"fs fs30 fw fw500 blueColor\">Desde el primer momento que tuvimos contacto con Atrys, cre\u00edmos que no podr\u00eda haber una relaci\u00f3n m\u00e1s fruct\u00edfera. <\/blockquote>\r\n\t\t\t\t\t\t\t<div class=\"text\">\r\n\t\t\t\t\t\t\t\t<h3 class=\"fs fs28 fw fw500 blueColor\">IBSAL<\/h3>\r\n\t\t\t\t\t\t\t\t<p class=\"fs fs16 fw fw100\">Prof. Juan Jes\u00fas Cruz Hern\u00e1ndez Coordinador del Grupo de C\u00e1ncer del Instituto de Investigaci\u00f3n Biom\u00e9dica de Salamanca<\/p>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div> <!-- End Slide item -->\r\n\t\t\t\t\t\t\t<div class=\"slide__item \">\r\n\t\t\t\t\t<!-- Slide item -->\r\n\t\t\t\t\t<div class=\"box\">\r\n\t\t\t\t\t\t<div class=\"cite\">\r\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.atryshealth.com\/wp-content\/themes\/atrys\/assets\/img\/comillasGreen.svg\">\r\n\t\t\t\t\t\t\t<div class=\"separator separator__20\"><\/div>\r\n\t\t\t\t\t\t\t<blockquote class=\"fs fs30 fw fw500 blueColor\">Gracias a sus habilidades, esfuerzo y eficacia, su colaboraci\u00f3n nos ha servido para hallar nuevos biomarcadores en diferentes tipos de c\u00e1ncer. Queremos seguir avanzando de la mano con Atrys.\r\n<\/blockquote>\r\n\t\t\t\t\t\t\t<div class=\"text\">\r\n\t\t\t\t\t\t\t\t<h3 class=\"fs fs28 fw fw500 blueColor\">Fundaci\u00f3n MEDINA<\/h3>\r\n\t\t\t\t\t\t\t\t<p class=\"fs fs16 fw fw100\">Francisca Vicente, PhD. Head area of Screening and Target Validation<\/p>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div> <!-- End Slide item -->\r\n\t\t\t\t\t<\/div> <!-- End Slider -->\r\n\t<\/div>\r\n<\/section> <!-- END SLIDE PARTNERS -->\r\n\r\n\n\n\r\n<section id=\"dondeEstamos2\" class=\"section section__dondeEstamos2\"> <!-- DONDE ESTAMOS2 -->\r\n\t<div class=\"container\">\r\n\t\t<div class=\"box box__text\">\r\n\t\t\t<span class=\"fs fs20 fw fw500 blueLightColor\">D\u00d3NDE ESTAMOS<\/span>\r\n\t\t\t<div class=\"separator separator__20\"><\/div>\r\n\t\t\t<h2 class=\"fs fs55 fw fw500 blueColor\"><p>Nuestros<br \/>\nlaboratorios<br \/>\nde investigaci\u00f3n<\/p>\n<\/h2>\r\n\t\t\t<div class=\"separator separator__60\"><\/div>\r\n\t\t\t\t\t\t<a class=\"fs fs16 fw fw500 button button__normal button__green uppercase\" href=\"https:\/\/atryshealth.com\/en-el-mundo\/?fespecialidad=id\" target=\"https:\/\/atryshealth.com\/en-el-mundo\/\" title=\"Ver centros\">Ver centros<\/a>\r\n\t\t<\/div>\r\n\t\t<div class=\"mask\">\r\n\t\t\t<img decoding=\"async\" src=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/09\/Laboratorios-de-investigacion.jpg\" alt=\"\">\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/section> <!-- END DONDE ESTAMOS2 -->\n\n<section id=\"contactar\" class=\"section section__contactar \" > <!-- CONTACTAR -->\r\n\t\t<div class=\"container\" >\r\n\t\t<div class=\"mask\" >\r\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/09\/Fill-1.png\" alt=\"\">\r\n\t\t\t\t\t<\/div>\r\n\t\t<div class=\"separator separator__40\" ><\/div>\r\n\t\t<div class=\"box box__text\">\r\n\t\t\t<h2 class=\"fs fs55 fw fw500 \" style=\"color: #044aab\" ><p>\u00bfQuieres ponerte en contacto con el departamento de I+D?<\/p>\n<\/h2>\r\n\t\t\t<div class=\"separator separator__20\" ><\/div>\r\n\t\t\t<p class=\"fs fs20 fw fw100\" style=\"color: #0a0a0a\" >Cu\u00e9ntanos en qu\u00e9 te podemos ayudar<\/p>\r\n\t\t<\/div>\r\n\t\t<div class=\"separator separator__60\" ><\/div>\r\n\t\t\t\t\t<div class=\"cover cover__buttons\">\r\n\t\t\t\t<a class=\"width-auto fs fs16 fw fw500 button button__small button__black  uppercase\" href=\"https:\/\/atryshealth.com\/contacto\/#i+d\" title=\"Contactar\" target=\"\">Contactar<\/a>\r\n\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n<\/section> <!-- END CONTACTAR -->\r\n","protected":false},"excerpt":{"rendered":"<p>Participa en la V Edici\u00f3n Premios C\u00e1tedra UB-Atrys Radioterapia Personalizada&nbsp;<\/p>\n","protected":false},"author":33,"featured_media":0,"parent":0,"menu_order":120,"comment_status":"closed","ping_status":"closed","template":"template-pages\/template-generic-page.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-462","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>I+D - Atrys Health<\/title>\n<meta name=\"description\" content=\"Somos una gran compa\u00f1\u00eda. Creamos nuevas soluciones para los pacientes y el sector sanitario. Miles de profesionales de Atrys ponemos nuestra experiencia al servicio de todos, para ofrecer diagn\u00f3sticos y tratamientos de precisi\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.atryshealth.com\/es\/id\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I+D - Atrys Health\" \/>\n<meta property=\"og:description\" content=\"Somos una gran compa\u00f1\u00eda. Creamos nuevas soluciones para los pacientes y el sector sanitario. Miles de profesionales de Atrys ponemos nuestra experiencia al servicio de todos, para ofrecer diagn\u00f3sticos y tratamientos de precisi\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.atryshealth.com\/es\/id\/\" \/>\n<meta property=\"og:site_name\" content=\"Atrys Health\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-13T08:16:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2026\/03\/cartel-premios-catedra-edited-1024x683.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Atrys_Health\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/id\\\/\",\"url\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/id\\\/\",\"name\":\"I+D - Atrys Health\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/id\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/id\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.atryshealth.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/cartel-premios-catedra-edited-1024x683.jpg\",\"datePublished\":\"2021-09-09T11:55:00+00:00\",\"dateModified\":\"2026-03-13T08:16:12+00:00\",\"description\":\"Somos una gran compa\u00f1\u00eda. Creamos nuevas soluciones para los pacientes y el sector sanitario. Miles de profesionales de Atrys ponemos nuestra experiencia al servicio de todos, para ofrecer diagn\u00f3sticos y tratamientos de precisi\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/id\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/id\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/id\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.atryshealth.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/cartel-premios-catedra-edited-1024x683.jpg\",\"contentUrl\":\"https:\\\/\\\/www.atryshealth.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/cartel-premios-catedra-edited-1024x683.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/id\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I+D\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/\",\"name\":\"Atrys Health\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/#organization\",\"name\":\"Atrys Health S.A.\",\"url\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.atryshealth.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/atrys-logo-probar-web.png\",\"contentUrl\":\"https:\\\/\\\/www.atryshealth.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/atrys-logo-probar-web.png\",\"width\":1563,\"height\":1014,\"caption\":\"Atrys Health S.A.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Atrys_Health\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/atrys-health\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCejhA_ghBXRG1xoe9HB9pEw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I+D - Atrys Health","description":"Somos una gran compa\u00f1\u00eda. Creamos nuevas soluciones para los pacientes y el sector sanitario. Miles de profesionales de Atrys ponemos nuestra experiencia al servicio de todos, para ofrecer diagn\u00f3sticos y tratamientos de precisi\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.atryshealth.com\/es\/id\/","og_locale":"es_ES","og_type":"article","og_title":"I+D - Atrys Health","og_description":"Somos una gran compa\u00f1\u00eda. Creamos nuevas soluciones para los pacientes y el sector sanitario. Miles de profesionales de Atrys ponemos nuestra experiencia al servicio de todos, para ofrecer diagn\u00f3sticos y tratamientos de precisi\u00f3n.","og_url":"https:\/\/www.atryshealth.com\/es\/id\/","og_site_name":"Atrys Health","article_modified_time":"2026-03-13T08:16:12+00:00","og_image":[{"url":"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2026\/03\/cartel-premios-catedra-edited-1024x683.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@Atrys_Health","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.atryshealth.com\/es\/id\/","url":"https:\/\/www.atryshealth.com\/es\/id\/","name":"I+D - Atrys Health","isPartOf":{"@id":"https:\/\/www.atryshealth.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.atryshealth.com\/es\/id\/#primaryimage"},"image":{"@id":"https:\/\/www.atryshealth.com\/es\/id\/#primaryimage"},"thumbnailUrl":"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2026\/03\/cartel-premios-catedra-edited-1024x683.jpg","datePublished":"2021-09-09T11:55:00+00:00","dateModified":"2026-03-13T08:16:12+00:00","description":"Somos una gran compa\u00f1\u00eda. Creamos nuevas soluciones para los pacientes y el sector sanitario. Miles de profesionales de Atrys ponemos nuestra experiencia al servicio de todos, para ofrecer diagn\u00f3sticos y tratamientos de precisi\u00f3n.","breadcrumb":{"@id":"https:\/\/www.atryshealth.com\/es\/id\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.atryshealth.com\/es\/id\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.atryshealth.com\/es\/id\/#primaryimage","url":"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2026\/03\/cartel-premios-catedra-edited-1024x683.jpg","contentUrl":"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2026\/03\/cartel-premios-catedra-edited-1024x683.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.atryshealth.com\/es\/id\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.atryshealth.com\/es\/"},{"@type":"ListItem","position":2,"name":"I+D"}]},{"@type":"WebSite","@id":"https:\/\/www.atryshealth.com\/es\/#website","url":"https:\/\/www.atryshealth.com\/es\/","name":"Atrys Health","description":"","publisher":{"@id":"https:\/\/www.atryshealth.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.atryshealth.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.atryshealth.com\/es\/#organization","name":"Atrys Health S.A.","url":"https:\/\/www.atryshealth.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.atryshealth.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/12\/atrys-logo-probar-web.png","contentUrl":"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/12\/atrys-logo-probar-web.png","width":1563,"height":1014,"caption":"Atrys Health S.A."},"image":{"@id":"https:\/\/www.atryshealth.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Atrys_Health","https:\/\/es.linkedin.com\/company\/atrys-health","https:\/\/www.youtube.com\/channel\/UCejhA_ghBXRG1xoe9HB9pEw"]}]}},"_links":{"self":[{"href":"https:\/\/www.atryshealth.com\/es\/wp-json\/wp\/v2\/pages\/462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.atryshealth.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.atryshealth.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.atryshealth.com\/es\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/www.atryshealth.com\/es\/wp-json\/wp\/v2\/comments?post=462"}],"version-history":[{"count":106,"href":"https:\/\/www.atryshealth.com\/es\/wp-json\/wp\/v2\/pages\/462\/revisions"}],"predecessor-version":[{"id":28118,"href":"https:\/\/www.atryshealth.com\/es\/wp-json\/wp\/v2\/pages\/462\/revisions\/28118"}],"wp:attachment":[{"href":"https:\/\/www.atryshealth.com\/es\/wp-json\/wp\/v2\/media?parent=462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}