{"id":4114,"date":"2016-07-20T00:00:00","date_gmt":"2016-07-20T00:00:00","guid":{"rendered":"https:\/\/atryshealth.com\/atrys-comenzar%c3%a1-a-cotizar-en-el-mercado-alternativo-burs%c3%a1til-el-22-de-julio_8873\/"},"modified":"2021-11-23T13:36:23","modified_gmt":"2021-11-23T12:36:23","slug":"atrys-comenzar%c3%a1-a-cotizar-en-el-mercado-alternativo-burs%c3%a1til-el-22-de-julio_8873","status":"publish","type":"nota-de-prensa","link":"https:\/\/www.atryshealth.com\/es\/nota-de-prensa\/atrys-comenzar%c3%a1-a-cotizar-en-el-mercado-alternativo-burs%c3%a1til-el-22-de-julio_8873\/","title":{"rendered":"Atrys comenzar\u00e1 a cotizar en el Mercado Alternativo Burs\u00e1til (MAB) el 22 de julio"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/11\/mercado-alternativo-bursatil-edited.jpg\" alt=\"\" class=\"wp-image-8777\" width=\"530\" srcset=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/11\/mercado-alternativo-bursatil-edited.jpg 326w, https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/11\/mercado-alternativo-bursatil-edited-300x181.jpg 300w\" sizes=\"(max-width: 326px) 100vw, 326px\" \/><\/figure><\/div>\n\n\n<p style=\"text-align: justify;\"><strong>Atrys Health, S.A., <\/strong>compa\u00f1\u00eda dedicada a la prestaci\u00f3n de servicios diagn\u00f3sticos y tratamientos m\u00e9dicos de excelencia, <strong>comenzar\u00e1 a cotizar en el Mercado Alternativo Burs\u00e1til (MAB) el pr\u00f3ximo viernes 22 de julio.<\/strong> El precio de emisi\u00f3n fijado para la ampliaci\u00f3n de capital supone asignar a Atrys una capitalizaci\u00f3n burs\u00e1til\u00a0 de 16,5 millones de euros.<\/p>\n<p>La compa\u00f1\u00eda ha realizado una emisi\u00f3n de nuevas acciones por un importe total de 4,5 millones de euros, tras emitir 3.040.541 t\u00edtulos, a un precio de 1,48 euros por acci\u00f3n. Las acciones nuevas estar\u00e1n representadas por anotaciones en cuenta y tendr\u00e1n los mismos derechos que las que est\u00e1n en circulaci\u00f3n en la actualidad.<\/p>\n<p>El presidente de Atrys, Santiago de Torres, ha explicado que la oferta de suscripci\u00f3n \u00abse ha cerrado en 4,5 millones de euros, lo que demuestra \u00a0el inter\u00e9s de los inversores por la compa\u00f1\u00eda antes de salir al mercado\u00bb. Por su parte, Isabel Lozano, Consejera Delegada de la sociedad, \u00a0ha indicado: \u00abla captaci\u00f3n de fondos fruto de la ampliaci\u00f3n de capital permitir\u00e1 financiar la apertura de nuevos centros de radioterapia, potenciar nuevos servicios diagn\u00f3sticos as\u00ed como la expansi\u00f3n internacional de la compa\u00f1\u00eda\u00bb. Adem\u00e1s, Santiago de Torres, ha destacado que la negociaci\u00f3n en el MAB \u00abpermitir\u00e1 aumentar la visibilidad de la empresa ante clientes, socios e inversores, fortaleciendo su posicionamiento y poniendo en valor sus altos est\u00e1ndares de calidad, su solvencia t\u00e9cnica y cient\u00edfica y su compromiso con la innovaci\u00f3n\u00bb.<\/p>\n<p>Los accionistas de\u00a0Atrys\u00a0tienen voluntad de continuar en el capital y han adquirido un compromiso de permanencia de 12 meses. Tras esta ampliaci\u00f3n de capital el\u00a029% de los t\u00edtulos de la compa\u00f1\u00eda est\u00e1\u00a0controlado por\u00a0Inveready, grupo de inversi\u00f3n de capital riesgo.\u00a0El equipo cient\u00edfico y gestor ostenta el 27% y el resto del accionariado est\u00e1 integrado por <em>family offices<\/em> e inversores institucionales.<\/p>\n<p>El c\u00f3digo de negociaci\u00f3n de la compa\u00f1\u00eda ser\u00e1 ATRY y la contrataci\u00f3n se realizar\u00e1 mediante <em>fixing<\/em> dos veces al d\u00eda. La compa\u00f1\u00eda ha designado como asesor registrado a\u00a0Norgesti\u00f3n. Adem\u00e1s,\u00a0Atrys \u00a0ha seleccionado como entidades colocadoras a Andbank e Intermoney.\u00a0Banco Sabadell\u00a0es el banco agente que actuar\u00e1 tambi\u00e9n como proveedor de liquidez y Ram\u00f3n y Cajal Abogados es el asesor legal.<\/p>\n<p>La compa\u00f1\u00eda\u00a0\u00a0cerr\u00f3 el ejercicio 2015\u00a0con una cifra de negocio\u00a0de\u00a02,9\u00a0millones de euros en Espa\u00f1a, un\u00a0163% m\u00e1s con respecto al a\u00f1o 2014,\u00a0y un\u00a0beneficio neto de\u00a01,3 millones de\u00a0euros.\u00a0<\/p>\n<p>Atrys es una compa\u00f1\u00eda innovadora dedicada a la prestaci\u00f3n de servicios diagn\u00f3sticos y tratamientos m\u00e9dicos de excelencia, que combina t\u00e9cnicas de diagn\u00f3stico de precisi\u00f3n en anatom\u00eda patol\u00f3gica y molecular y de diagn\u00f3stico por imagen online, a trav\u00e9s de su propia plataforma tecnol\u00f3gica multi-especialidad, con nuevos tratamientos de radioterapia oncol\u00f3gica.<\/p>\n<p>Atrys tiene el objetivo de aplicar los m\u00e9todos m\u00e1s avanzados de diagn\u00f3stico y tratamiento del c\u00e1ncer. El compromiso de la Compa\u00f1\u00eda es llevar la excelencia m\u00e9dica al mayor n\u00famero de pacientes posibles, mediante la aplicaci\u00f3n de las \u00faltimas tecnolog\u00edas y el conocimiento cient\u00edfico m\u00e1s avanzado.<\/p>\n<p>La compa\u00f1\u00eda ofrece asimismo servicios de diagn\u00f3stico online de imagen m\u00e9dica en diferentes especialidades, a trav\u00e9s de su propia plataforma, como radiolog\u00eda, cardiolog\u00eda, oftalmolog\u00eda y dermatolog\u00eda. Estos servicios permiten deslocalizar el informe del especialista del centro en el que se realiza la prueba.<\/p>\n<p>Atrys realiza una gesti\u00f3n integrada de la enfermedad oncol\u00f3gica, desde el diagn\u00f3stico individualizado (patol\u00f3gico, molecular, gen\u00e9tico y radiol\u00f3gico),\u00a0 hasta\u00a0 la radioterapia hipo-fraccionada o de Dosis \u00danica a aquellos pacientes susceptibles de beneficiarse de este tratamiento, mediante acuerdos de colaboraci\u00f3n con centros sanitarios\u00a0 de referencia.<\/p>\n<p>La compa\u00f1\u00eda, cuya sede se localiza en Madrid, cuenta con dos laboratorios principales, dotados con los equipos y las tecnolog\u00edas necesarios para el diagn\u00f3stico y la investigaci\u00f3n, situados en Barcelona y en el Centro Genyo de Granada.<\/p>\n<p>Asimismo, Atrys desarrolla proyectos de I+D aplicada que han generado diversas familias de patentes, en colaboraci\u00f3n con centros de referencia nacionales e internacionales, dirigida a la mejora de los sistemas diagn\u00f3sticos y las modalidades de tratamiento, lo que permite a la Compa\u00f1\u00eda incorporar los \u00faltimos avances cient\u00edficos a su pr\u00e1ctica cl\u00ednica.<\/p>","protected":false},"excerpt":{"rendered":"<p>Capta 4,5 millones de euros \u00a0a trav\u00e9s de la ampliaci\u00f3n de capital previa a su salida al MAB.<\/p>\n<p>El precio de la emisi\u00f3n es de 1,48 euros por t\u00edtulo.<\/p>\n<p>Los socios fundadores y accionistas previos a la ampliaci\u00f3n mantienen un compromiso de permanencia de 12 meses.<\/p>\n<p>\u00a0<\/p>\n","protected":false},"template":"","class_list":["post-4114","nota-de-prensa","type-nota-de-prensa","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Atrys comenzar\u00e1 a cotizar en el Mercado Alternativo Burs\u00e1til (MAB) el 22 de julio - Atrys Health<\/title>\n<meta name=\"description\" content=\"Somos una gran compa\u00f1\u00eda. Creamos nuevas soluciones para los pacientes y el sector sanitario. Miles de profesionales de Atrys ponemos nuestra experiencia al servicio de todos, para ofrecer diagn\u00f3sticos y tratamientos de precisi\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.atryshealth.com\/es\/nota-de-prensa\/atrys-comenzar\u00e1-a-cotizar-en-el-mercado-alternativo-burs\u00e1til-el-22-de-julio_8873\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Atrys comenzar\u00e1 a cotizar en el Mercado Alternativo Burs\u00e1til (MAB) el 22 de julio - Atrys Health\" \/>\n<meta property=\"og:description\" content=\"Somos una gran compa\u00f1\u00eda. Creamos nuevas soluciones para los pacientes y el sector sanitario. Miles de profesionales de Atrys ponemos nuestra experiencia al servicio de todos, para ofrecer diagn\u00f3sticos y tratamientos de precisi\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.atryshealth.com\/es\/nota-de-prensa\/atrys-comenzar\u00e1-a-cotizar-en-el-mercado-alternativo-burs\u00e1til-el-22-de-julio_8873\/\" \/>\n<meta property=\"og:site_name\" content=\"Atrys Health\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-23T12:36:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/11\/mercado-alternativo-bursatil-edited.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Atrys_Health\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/nota-de-prensa\\\/atrys-comenzar%c3%a1-a-cotizar-en-el-mercado-alternativo-burs%c3%a1til-el-22-de-julio_8873\\\/\",\"url\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/nota-de-prensa\\\/atrys-comenzar%c3%a1-a-cotizar-en-el-mercado-alternativo-burs%c3%a1til-el-22-de-julio_8873\\\/\",\"name\":\"Atrys comenzar\u00e1 a cotizar en el Mercado Alternativo Burs\u00e1til (MAB) el 22 de julio - Atrys Health\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/nota-de-prensa\\\/atrys-comenzar%c3%a1-a-cotizar-en-el-mercado-alternativo-burs%c3%a1til-el-22-de-julio_8873\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/nota-de-prensa\\\/atrys-comenzar%c3%a1-a-cotizar-en-el-mercado-alternativo-burs%c3%a1til-el-22-de-julio_8873\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.atryshealth.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/mercado-alternativo-bursatil-edited.jpg\",\"datePublished\":\"2016-07-20T00:00:00+00:00\",\"dateModified\":\"2021-11-23T12:36:23+00:00\",\"description\":\"Somos una gran compa\u00f1\u00eda. Creamos nuevas soluciones para los pacientes y el sector sanitario. Miles de profesionales de Atrys ponemos nuestra experiencia al servicio de todos, para ofrecer diagn\u00f3sticos y tratamientos de precisi\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/nota-de-prensa\\\/atrys-comenzar%c3%a1-a-cotizar-en-el-mercado-alternativo-burs%c3%a1til-el-22-de-julio_8873\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/nota-de-prensa\\\/atrys-comenzar%c3%a1-a-cotizar-en-el-mercado-alternativo-burs%c3%a1til-el-22-de-julio_8873\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/nota-de-prensa\\\/atrys-comenzar%c3%a1-a-cotizar-en-el-mercado-alternativo-burs%c3%a1til-el-22-de-julio_8873\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.atryshealth.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/mercado-alternativo-bursatil-edited.jpg\",\"contentUrl\":\"https:\\\/\\\/www.atryshealth.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/mercado-alternativo-bursatil-edited.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/nota-de-prensa\\\/atrys-comenzar%c3%a1-a-cotizar-en-el-mercado-alternativo-burs%c3%a1til-el-22-de-julio_8873\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Notas de prensa\",\"item\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/nota-de-prensa\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Atrys comenzar\u00e1 a cotizar en el Mercado Alternativo Burs\u00e1til (MAB) el 22 de julio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/\",\"name\":\"Atrys Health\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/#organization\",\"name\":\"Atrys Health S.A.\",\"url\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.atryshealth.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/atrys-logo-probar-web.png\",\"contentUrl\":\"https:\\\/\\\/www.atryshealth.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/atrys-logo-probar-web.png\",\"width\":1563,\"height\":1014,\"caption\":\"Atrys Health S.A.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Atrys_Health\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/atrys-health\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCejhA_ghBXRG1xoe9HB9pEw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Atrys comenzar\u00e1 a cotizar en el Mercado Alternativo Burs\u00e1til (MAB) el 22 de julio - Atrys Health","description":"Somos una gran compa\u00f1\u00eda. Creamos nuevas soluciones para los pacientes y el sector sanitario. Miles de profesionales de Atrys ponemos nuestra experiencia al servicio de todos, para ofrecer diagn\u00f3sticos y tratamientos de precisi\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.atryshealth.com\/es\/nota-de-prensa\/atrys-comenzar\u00e1-a-cotizar-en-el-mercado-alternativo-burs\u00e1til-el-22-de-julio_8873\/","og_locale":"es_ES","og_type":"article","og_title":"Atrys comenzar\u00e1 a cotizar en el Mercado Alternativo Burs\u00e1til (MAB) el 22 de julio - Atrys Health","og_description":"Somos una gran compa\u00f1\u00eda. Creamos nuevas soluciones para los pacientes y el sector sanitario. Miles de profesionales de Atrys ponemos nuestra experiencia al servicio de todos, para ofrecer diagn\u00f3sticos y tratamientos de precisi\u00f3n.","og_url":"https:\/\/www.atryshealth.com\/es\/nota-de-prensa\/atrys-comenzar\u00e1-a-cotizar-en-el-mercado-alternativo-burs\u00e1til-el-22-de-julio_8873\/","og_site_name":"Atrys Health","article_modified_time":"2021-11-23T12:36:23+00:00","og_image":[{"url":"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/11\/mercado-alternativo-bursatil-edited.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@Atrys_Health","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.atryshealth.com\/es\/nota-de-prensa\/atrys-comenzar%c3%a1-a-cotizar-en-el-mercado-alternativo-burs%c3%a1til-el-22-de-julio_8873\/","url":"https:\/\/www.atryshealth.com\/es\/nota-de-prensa\/atrys-comenzar%c3%a1-a-cotizar-en-el-mercado-alternativo-burs%c3%a1til-el-22-de-julio_8873\/","name":"Atrys comenzar\u00e1 a cotizar en el Mercado Alternativo Burs\u00e1til (MAB) el 22 de julio - Atrys Health","isPartOf":{"@id":"https:\/\/www.atryshealth.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.atryshealth.com\/es\/nota-de-prensa\/atrys-comenzar%c3%a1-a-cotizar-en-el-mercado-alternativo-burs%c3%a1til-el-22-de-julio_8873\/#primaryimage"},"image":{"@id":"https:\/\/www.atryshealth.com\/es\/nota-de-prensa\/atrys-comenzar%c3%a1-a-cotizar-en-el-mercado-alternativo-burs%c3%a1til-el-22-de-julio_8873\/#primaryimage"},"thumbnailUrl":"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/11\/mercado-alternativo-bursatil-edited.jpg","datePublished":"2016-07-20T00:00:00+00:00","dateModified":"2021-11-23T12:36:23+00:00","description":"Somos una gran compa\u00f1\u00eda. Creamos nuevas soluciones para los pacientes y el sector sanitario. Miles de profesionales de Atrys ponemos nuestra experiencia al servicio de todos, para ofrecer diagn\u00f3sticos y tratamientos de precisi\u00f3n.","breadcrumb":{"@id":"https:\/\/www.atryshealth.com\/es\/nota-de-prensa\/atrys-comenzar%c3%a1-a-cotizar-en-el-mercado-alternativo-burs%c3%a1til-el-22-de-julio_8873\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.atryshealth.com\/es\/nota-de-prensa\/atrys-comenzar%c3%a1-a-cotizar-en-el-mercado-alternativo-burs%c3%a1til-el-22-de-julio_8873\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.atryshealth.com\/es\/nota-de-prensa\/atrys-comenzar%c3%a1-a-cotizar-en-el-mercado-alternativo-burs%c3%a1til-el-22-de-julio_8873\/#primaryimage","url":"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/11\/mercado-alternativo-bursatil-edited.jpg","contentUrl":"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/11\/mercado-alternativo-bursatil-edited.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.atryshealth.com\/es\/nota-de-prensa\/atrys-comenzar%c3%a1-a-cotizar-en-el-mercado-alternativo-burs%c3%a1til-el-22-de-julio_8873\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.atryshealth.com\/es\/"},{"@type":"ListItem","position":2,"name":"Notas de prensa","item":"https:\/\/www.atryshealth.com\/es\/nota-de-prensa\/"},{"@type":"ListItem","position":3,"name":"Atrys comenzar\u00e1 a cotizar en el Mercado Alternativo Burs\u00e1til (MAB) el 22 de julio"}]},{"@type":"WebSite","@id":"https:\/\/www.atryshealth.com\/es\/#website","url":"https:\/\/www.atryshealth.com\/es\/","name":"Atrys Health","description":"","publisher":{"@id":"https:\/\/www.atryshealth.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.atryshealth.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.atryshealth.com\/es\/#organization","name":"Atrys Health S.A.","url":"https:\/\/www.atryshealth.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.atryshealth.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/12\/atrys-logo-probar-web.png","contentUrl":"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/12\/atrys-logo-probar-web.png","width":1563,"height":1014,"caption":"Atrys Health S.A."},"image":{"@id":"https:\/\/www.atryshealth.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Atrys_Health","https:\/\/es.linkedin.com\/company\/atrys-health","https:\/\/www.youtube.com\/channel\/UCejhA_ghBXRG1xoe9HB9pEw"]}]}},"_links":{"self":[{"href":"https:\/\/www.atryshealth.com\/es\/wp-json\/wp\/v2\/nota-de-prensa\/4114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.atryshealth.com\/es\/wp-json\/wp\/v2\/nota-de-prensa"}],"about":[{"href":"https:\/\/www.atryshealth.com\/es\/wp-json\/wp\/v2\/types\/nota-de-prensa"}],"wp:attachment":[{"href":"https:\/\/www.atryshealth.com\/es\/wp-json\/wp\/v2\/media?parent=4114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}