{"id":18753,"date":"2023-03-21T17:28:21","date_gmt":"2023-03-21T16:28:21","guid":{"rendered":"https:\/\/www.atryshealth.com\/?post_type=evento&#038;p=18753"},"modified":"2023-04-29T16:41:02","modified_gmt":"2023-04-29T14:41:02","slug":"webinar-de-presentacion-de-resultados-anuales-2022","status":"publish","type":"evento","link":"https:\/\/www.atryshealth.com\/es\/evento\/webinar-de-presentacion-de-resultados-anuales-2022\/","title":{"rendered":"Webinar de Presentaci\u00f3n de resultados anuales 2022"},"content":{"rendered":"","protected":false},"template":"","class_list":["post-18753","evento","type-evento","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Webinar de Presentaci\u00f3n de resultados anuales 2022 - Atrys Health<\/title>\n<meta name=\"description\" content=\"Somos una gran compa\u00f1\u00eda. Creamos nuevas soluciones para los pacientes y el sector sanitario. Miles de profesionales de Atrys ponemos nuestra experiencia al servicio de todos, para ofrecer diagn\u00f3sticos y tratamientos de precisi\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.atryshealth.com\/es\/evento\/webinar-de-presentacion-de-resultados-anuales-2022\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Webinar de Presentaci\u00f3n de resultados anuales 2022 - Atrys Health\" \/>\n<meta property=\"og:description\" content=\"Somos una gran compa\u00f1\u00eda. Creamos nuevas soluciones para los pacientes y el sector sanitario. Miles de profesionales de Atrys ponemos nuestra experiencia al servicio de todos, para ofrecer diagn\u00f3sticos y tratamientos de precisi\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.atryshealth.com\/es\/evento\/webinar-de-presentacion-de-resultados-anuales-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Atrys Health\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-29T14:41:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/12\/atrys-logo-probar-web.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1563\" \/>\n\t<meta property=\"og:image:height\" content=\"1014\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Atrys_Health\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/evento\\\/webinar-de-presentacion-de-resultados-anuales-2022\\\/\",\"url\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/evento\\\/webinar-de-presentacion-de-resultados-anuales-2022\\\/\",\"name\":\"Webinar de Presentaci\u00f3n de resultados anuales 2022 - Atrys Health\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/#website\"},\"datePublished\":\"2023-03-21T16:28:21+00:00\",\"dateModified\":\"2023-04-29T14:41:02+00:00\",\"description\":\"Somos una gran compa\u00f1\u00eda. Creamos nuevas soluciones para los pacientes y el sector sanitario. Miles de profesionales de Atrys ponemos nuestra experiencia al servicio de todos, para ofrecer diagn\u00f3sticos y tratamientos de precisi\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/evento\\\/webinar-de-presentacion-de-resultados-anuales-2022\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/evento\\\/webinar-de-presentacion-de-resultados-anuales-2022\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/evento\\\/webinar-de-presentacion-de-resultados-anuales-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Webinar de Presentaci\u00f3n de resultados anuales 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/\",\"name\":\"Atrys Health\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/#organization\",\"name\":\"Atrys Health S.A.\",\"url\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.atryshealth.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/atrys-logo-probar-web.png\",\"contentUrl\":\"https:\\\/\\\/www.atryshealth.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/atrys-logo-probar-web.png\",\"width\":1563,\"height\":1014,\"caption\":\"Atrys Health S.A.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Atrys_Health\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/atrys-health\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCejhA_ghBXRG1xoe9HB9pEw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Webinar de Presentaci\u00f3n de resultados anuales 2022 - Atrys Health","description":"Somos una gran compa\u00f1\u00eda. Creamos nuevas soluciones para los pacientes y el sector sanitario. Miles de profesionales de Atrys ponemos nuestra experiencia al servicio de todos, para ofrecer diagn\u00f3sticos y tratamientos de precisi\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.atryshealth.com\/es\/evento\/webinar-de-presentacion-de-resultados-anuales-2022\/","og_locale":"es_ES","og_type":"article","og_title":"Webinar de Presentaci\u00f3n de resultados anuales 2022 - Atrys Health","og_description":"Somos una gran compa\u00f1\u00eda. Creamos nuevas soluciones para los pacientes y el sector sanitario. Miles de profesionales de Atrys ponemos nuestra experiencia al servicio de todos, para ofrecer diagn\u00f3sticos y tratamientos de precisi\u00f3n.","og_url":"https:\/\/www.atryshealth.com\/es\/evento\/webinar-de-presentacion-de-resultados-anuales-2022\/","og_site_name":"Atrys Health","article_modified_time":"2023-04-29T14:41:02+00:00","og_image":[{"width":1563,"height":1014,"url":"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/12\/atrys-logo-probar-web.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Atrys_Health","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.atryshealth.com\/es\/evento\/webinar-de-presentacion-de-resultados-anuales-2022\/","url":"https:\/\/www.atryshealth.com\/es\/evento\/webinar-de-presentacion-de-resultados-anuales-2022\/","name":"Webinar de Presentaci\u00f3n de resultados anuales 2022 - Atrys Health","isPartOf":{"@id":"https:\/\/www.atryshealth.com\/es\/#website"},"datePublished":"2023-03-21T16:28:21+00:00","dateModified":"2023-04-29T14:41:02+00:00","description":"Somos una gran compa\u00f1\u00eda. Creamos nuevas soluciones para los pacientes y el sector sanitario. Miles de profesionales de Atrys ponemos nuestra experiencia al servicio de todos, para ofrecer diagn\u00f3sticos y tratamientos de precisi\u00f3n.","breadcrumb":{"@id":"https:\/\/www.atryshealth.com\/es\/evento\/webinar-de-presentacion-de-resultados-anuales-2022\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.atryshealth.com\/es\/evento\/webinar-de-presentacion-de-resultados-anuales-2022\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.atryshealth.com\/es\/evento\/webinar-de-presentacion-de-resultados-anuales-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.atryshealth.com\/es\/"},{"@type":"ListItem","position":2,"name":"Webinar de Presentaci\u00f3n de resultados anuales 2022"}]},{"@type":"WebSite","@id":"https:\/\/www.atryshealth.com\/es\/#website","url":"https:\/\/www.atryshealth.com\/es\/","name":"Atrys Health","description":"","publisher":{"@id":"https:\/\/www.atryshealth.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.atryshealth.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.atryshealth.com\/es\/#organization","name":"Atrys Health S.A.","url":"https:\/\/www.atryshealth.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.atryshealth.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/12\/atrys-logo-probar-web.png","contentUrl":"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/12\/atrys-logo-probar-web.png","width":1563,"height":1014,"caption":"Atrys Health S.A."},"image":{"@id":"https:\/\/www.atryshealth.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Atrys_Health","https:\/\/es.linkedin.com\/company\/atrys-health","https:\/\/www.youtube.com\/channel\/UCejhA_ghBXRG1xoe9HB9pEw"]}]}},"_links":{"self":[{"href":"https:\/\/www.atryshealth.com\/es\/wp-json\/wp\/v2\/evento\/18753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.atryshealth.com\/es\/wp-json\/wp\/v2\/evento"}],"about":[{"href":"https:\/\/www.atryshealth.com\/es\/wp-json\/wp\/v2\/types\/evento"}],"wp:attachment":[{"href":"https:\/\/www.atryshealth.com\/es\/wp-json\/wp\/v2\/media?parent=18753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}