{"id":13028,"date":"2021-09-23T09:31:35","date_gmt":"2021-09-23T09:31:35","guid":{"rendered":"https:\/\/www.atryshealth.com\/servicio\/if-directa-piel\/"},"modified":"2021-09-23T09:31:35","modified_gmt":"2021-09-23T09:31:35","slug":"if-directa-piel","status":"publish","type":"servicio","link":"https:\/\/www.atryshealth.com\/en\/servicio\/if-directa-piel\/","title":{"rendered":"IF directa piel"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":4823,"template":"","patologia":[180,198],"class_list":["post-13028","servicio","type-servicio","status-publish","has-post-thumbnail","hentry","patologia-complementary-studies","patologia-immunofluorescence"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IF directa piel - Atrys Health<\/title>\n<meta name=\"description\" content=\"Somos una gran compa\u00f1\u00eda. Creamos nuevas soluciones para los pacientes y el sector sanitario. Miles de profesionales de Atrys ponemos nuestra experiencia al servicio de todos, para ofrecer diagn\u00f3sticos y tratamientos de precisi\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.atryshealth.com\/en\/servicio\/if-directa-piel\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IF directa piel - Atrys Health\" \/>\n<meta property=\"og:description\" content=\"Somos una gran compa\u00f1\u00eda. Creamos nuevas soluciones para los pacientes y el sector sanitario. Miles de profesionales de Atrys ponemos nuestra experiencia al servicio de todos, para ofrecer diagn\u00f3sticos y tratamientos de precisi\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.atryshealth.com\/en\/servicio\/if-directa-piel\/\" \/>\n<meta property=\"og:site_name\" content=\"Atrys Health\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/12\/atrys-logo-probar-web.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1563\" \/>\n\t<meta property=\"og:image:height\" content=\"1014\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Atrys_Health\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/en\\\/servicio\\\/if-directa-piel\\\/\",\"url\":\"https:\\\/\\\/www.atryshealth.com\\\/en\\\/servicio\\\/if-directa-piel\\\/\",\"name\":\"IF directa piel - Atrys Health\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/en\\\/servicio\\\/if-directa-piel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/en\\\/servicio\\\/if-directa-piel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.atryshealth.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/noticia2.jpg\",\"datePublished\":\"2021-09-23T09:31:35+00:00\",\"description\":\"Somos una gran compa\u00f1\u00eda. Creamos nuevas soluciones para los pacientes y el sector sanitario. Miles de profesionales de Atrys ponemos nuestra experiencia al servicio de todos, para ofrecer diagn\u00f3sticos y tratamientos de precisi\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/en\\\/servicio\\\/if-directa-piel\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.atryshealth.com\\\/en\\\/servicio\\\/if-directa-piel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/en\\\/servicio\\\/if-directa-piel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.atryshealth.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/noticia2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.atryshealth.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/noticia2.jpg\",\"width\":350,\"height\":363},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/en\\\/servicio\\\/if-directa-piel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.atryshealth.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Servicios\",\"item\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/servicio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"IF directa piel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/\",\"name\":\"Atrys Health\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/#organization\",\"name\":\"Atrys Health S.A.\",\"url\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.atryshealth.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/atrys-logo-probar-web.png\",\"contentUrl\":\"https:\\\/\\\/www.atryshealth.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/atrys-logo-probar-web.png\",\"width\":1563,\"height\":1014,\"caption\":\"Atrys Health S.A.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.atryshealth.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Atrys_Health\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/atrys-health\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCejhA_ghBXRG1xoe9HB9pEw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IF directa piel - Atrys Health","description":"Somos una gran compa\u00f1\u00eda. Creamos nuevas soluciones para los pacientes y el sector sanitario. Miles de profesionales de Atrys ponemos nuestra experiencia al servicio de todos, para ofrecer diagn\u00f3sticos y tratamientos de precisi\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.atryshealth.com\/en\/servicio\/if-directa-piel\/","og_locale":"en_US","og_type":"article","og_title":"IF directa piel - Atrys Health","og_description":"Somos una gran compa\u00f1\u00eda. Creamos nuevas soluciones para los pacientes y el sector sanitario. Miles de profesionales de Atrys ponemos nuestra experiencia al servicio de todos, para ofrecer diagn\u00f3sticos y tratamientos de precisi\u00f3n.","og_url":"https:\/\/www.atryshealth.com\/en\/servicio\/if-directa-piel\/","og_site_name":"Atrys Health","og_image":[{"width":1563,"height":1014,"url":"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/12\/atrys-logo-probar-web.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Atrys_Health","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.atryshealth.com\/en\/servicio\/if-directa-piel\/","url":"https:\/\/www.atryshealth.com\/en\/servicio\/if-directa-piel\/","name":"IF directa piel - Atrys Health","isPartOf":{"@id":"https:\/\/www.atryshealth.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.atryshealth.com\/en\/servicio\/if-directa-piel\/#primaryimage"},"image":{"@id":"https:\/\/www.atryshealth.com\/en\/servicio\/if-directa-piel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/09\/noticia2.jpg","datePublished":"2021-09-23T09:31:35+00:00","description":"Somos una gran compa\u00f1\u00eda. Creamos nuevas soluciones para los pacientes y el sector sanitario. Miles de profesionales de Atrys ponemos nuestra experiencia al servicio de todos, para ofrecer diagn\u00f3sticos y tratamientos de precisi\u00f3n.","breadcrumb":{"@id":"https:\/\/www.atryshealth.com\/en\/servicio\/if-directa-piel\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.atryshealth.com\/en\/servicio\/if-directa-piel\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.atryshealth.com\/en\/servicio\/if-directa-piel\/#primaryimage","url":"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/09\/noticia2.jpg","contentUrl":"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/09\/noticia2.jpg","width":350,"height":363},{"@type":"BreadcrumbList","@id":"https:\/\/www.atryshealth.com\/en\/servicio\/if-directa-piel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.atryshealth.com\/en\/"},{"@type":"ListItem","position":2,"name":"Servicios","item":"https:\/\/www.atryshealth.com\/es\/servicio\/"},{"@type":"ListItem","position":3,"name":"IF directa piel"}]},{"@type":"WebSite","@id":"https:\/\/www.atryshealth.com\/es\/#website","url":"https:\/\/www.atryshealth.com\/es\/","name":"Atrys Health","description":"","publisher":{"@id":"https:\/\/www.atryshealth.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.atryshealth.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.atryshealth.com\/es\/#organization","name":"Atrys Health S.A.","url":"https:\/\/www.atryshealth.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.atryshealth.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/12\/atrys-logo-probar-web.png","contentUrl":"https:\/\/www.atryshealth.com\/wp-content\/uploads\/2021\/12\/atrys-logo-probar-web.png","width":1563,"height":1014,"caption":"Atrys Health S.A."},"image":{"@id":"https:\/\/www.atryshealth.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Atrys_Health","https:\/\/es.linkedin.com\/company\/atrys-health","https:\/\/www.youtube.com\/channel\/UCejhA_ghBXRG1xoe9HB9pEw"]}]}},"_links":{"self":[{"href":"https:\/\/www.atryshealth.com\/en\/wp-json\/wp\/v2\/servicio\/13028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.atryshealth.com\/en\/wp-json\/wp\/v2\/servicio"}],"about":[{"href":"https:\/\/www.atryshealth.com\/en\/wp-json\/wp\/v2\/types\/servicio"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.atryshealth.com\/en\/wp-json\/wp\/v2\/media\/4823"}],"wp:attachment":[{"href":"https:\/\/www.atryshealth.com\/en\/wp-json\/wp\/v2\/media?parent=13028"}],"wp:term":[{"taxonomy":"patologia","embeddable":true,"href":"https:\/\/www.atryshealth.com\/en\/wp-json\/wp\/v2\/patologia?post=13028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}